{"id":42760,"date":"2025-09-30T09:36:53","date_gmt":"2025-09-30T09:36:53","guid":{"rendered":"https:\/\/lovme.pt\/?post_type=product&p=42760"},"modified":"2026-05-13T16:18:55","modified_gmt":"2026-05-13T16:18:55","slug":"get-real-double-dong-40-cm-pele","status":"publish","type":"product","link":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/","title":{"rendered":"GET REAL &#8211; DOUBLE DONG 40 CM PELE"},"content":{"rendered":"<p>O Double Dong da cole\u00e7\u00e3o Get Real \u00e9 um dong realista com duas pontas para divers\u00e3o \u00edntima sem fim!<\/p>\n<p> Este design realista apresenta uma silhueta dupla para o dobro do prazer \u00edntimo. Use sozinho ou compartilhe a satisfa\u00e7\u00e3o com um parceiro: a escolha safada \u00e9 toda sua!<\/p>\n<p> O Double Dong \u00e9 seguro para o corpo e \u00e9 feito de PVC de qualidade sem ftalatos.<\/p>\n<p> Detalhes flex\u00edveis, mas firmes, realistas e toque suave, mas com a quantidade certa de dureza: este sexy Double Dong preenche todos os requisitos certos.<\/p>\n<p> Se voc\u00ea quer prazer duplo e estimula\u00e7\u00e3o dupla, \u00e9 hora do favorito Get Real!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GET REAL &#8211; DOUBLE DONG 40 CM PELE<\/p>\n","protected":false},"featured_media":54688,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,56],"product_tag":[],"class_list":{"0":"post-42760","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brinquedos-de-bem-estar-sexual","7":"product_cat-dildos-e-arneses","8":"yith_product_brand-get-real","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GET REAL - DOUBLE DONG 40 CM PELE - Lovme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GET REAL - DOUBLE DONG 40 CM PELE - Lovme\" \/>\n<meta property=\"og:description\" content=\"GET REAL - DOUBLE DONG 40 CM PELE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/\" \/>\n<meta property=\"og:site_name\" content=\"Lovme\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T16:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/erki24nd3ub.exactdn.com\/wp-content\/uploads\/dream\/img\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/\",\"url\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/\",\"name\":\"GET REAL - DOUBLE DONG 40 CM PELE - Lovme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lovme.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erki24nd3ub.exactdn.com\\\/wp-content\\\/uploads\\\/dream\\\/img\\\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all\",\"datePublished\":\"2025-09-30T09:36:53+00:00\",\"dateModified\":\"2026-05-13T16:18:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erki24nd3ub.exactdn.com\\\/wp-content\\\/uploads\\\/dream\\\/img\\\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all\",\"contentUrl\":\"https:\\\/\\\/erki24nd3ub.exactdn.com\\\/wp-content\\\/uploads\\\/dream\\\/img\\\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/produto\\\/get-real-double-dong-40-cm-pele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lovme.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lovme.pt\\\/index.php\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GET REAL &#8211; DOUBLE DONG 40 CM PELE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lovme.pt\\\/#website\",\"url\":\"https:\\\/\\\/lovme.pt\\\/\",\"name\":\"Lovme Loja Er\u00f3tica N\u00ba1 em Portugal\",\"description\":\"A melhor loja er\u00f3tica de Portugal.\",\"alternateName\":\"Loja Er\u00f3tica Lovme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lovme.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GET REAL - DOUBLE DONG 40 CM PELE - Lovme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/","og_locale":"pt_PT","og_type":"article","og_title":"GET REAL - DOUBLE DONG 40 CM PELE - Lovme","og_description":"GET REAL - DOUBLE DONG 40 CM PELE","og_url":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/","og_site_name":"Lovme","article_modified_time":"2026-05-13T16:18:55+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/erki24nd3ub.exactdn.com\/wp-content\/uploads\/dream\/img\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/","url":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/","name":"GET REAL - DOUBLE DONG 40 CM PELE - Lovme","isPartOf":{"@id":"https:\/\/lovme.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/#primaryimage"},"image":{"@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/#primaryimage"},"thumbnailUrl":"https:\/\/erki24nd3ub.exactdn.com\/wp-content\/uploads\/dream\/img\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all","datePublished":"2025-09-30T09:36:53+00:00","dateModified":"2026-05-13T16:18:55+00:00","breadcrumb":{"@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/#primaryimage","url":"https:\/\/erki24nd3ub.exactdn.com\/wp-content\/uploads\/dream\/img\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all","contentUrl":"https:\/\/erki24nd3ub.exactdn.com\/wp-content\/uploads\/dream\/img\/img_140459_ffa2e975d8ba1f97ae0c6cb0c08861e9_1.jpg?strip=all","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/lovme.pt\/index.php\/produto\/get-real-double-dong-40-cm-pele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lovme.pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lovme.pt\/index.php\/loja\/"},{"@type":"ListItem","position":3,"name":"GET REAL &#8211; DOUBLE DONG 40 CM PELE"}]},{"@type":"WebSite","@id":"https:\/\/lovme.pt\/#website","url":"https:\/\/lovme.pt\/","name":"Lovme Loja Er\u00f3tica N\u00ba1 em Portugal","description":"A melhor loja er\u00f3tica de Portugal.","alternateName":"Loja Er\u00f3tica Lovme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lovme.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/product\/42760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/media\/54688"}],"wp:attachment":[{"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/media?parent=42760"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/product_brand?post=42760"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/product_cat?post=42760"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lovme.pt\/index.php\/wp-json\/wp\/v2\/product_tag?post=42760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}